{"id":6973,"date":"2023-07-19T07:25:22","date_gmt":"2023-07-19T05:25:22","guid":{"rendered":"https:\/\/www.ruede.de\/datenschutz\/"},"modified":"2024-06-18T15:28:42","modified_gmt":"2024-06-18T13:28:42","slug":"protection-des-donnees","status":"publish","type":"page","link":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/","title":{"rendered":"Protection des donn\u00e9es"},"content":{"rendered":"<div>\n<h1>D\u00e9claration de confidentialit\u00e9<\/h1>\n<h2>1.Aper\u00e7u de la protection des donn\u00e9es<\/h2>\n<h3>Remarques g\u00e9n\u00e9rales<\/h3>\n<p>Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement. Vous trouverez des informations d\u00e9taill\u00e9es sur le th\u00e8me de la protection des donn\u00e9es dans notre d\u00e9claration de protection des donn\u00e9es figurant sous ce texte.<\/p>\n<h3>Collecte de donn\u00e9es sur ce site web<\/h3>\n<h4>Qui est responsable de la collecte des donn\u00e9es sur ce site ?<\/h4>\n<p>Le traitement des donn\u00e9es sur ce site web est effectu\u00e9 par l&#8217;exploitant du site web. Vous trouverez les coordonn\u00e9es de ce dernier dans la section &#8220;Informations sur le responsable du traitement&#8221; de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<h4>Comment recueillons-nous vos donn\u00e9es ?<\/h4>\n<p>Vos donn\u00e9es sont collect\u00e9es, d&#8217;une part, lorsque vous nous les communiquez. Il peut s&#8217;agir, par exemple, de donn\u00e9es que vous saisissez dans un formulaire de contact.<\/p>\n<p>D&#8217;autres donn\u00e9es sont collect\u00e9es automatiquement ou apr\u00e8s votre accord par nos syst\u00e8mes informatiques lorsque vous visitez le site web. Il s&#8217;agit principalement de donn\u00e9es techniques (par exemple, le navigateur Internet, le syst\u00e8me d&#8217;exploitation ou l&#8217;heure de consultation de la page). La saisie de ces donn\u00e9es s&#8217;effectue automatiquement d\u00e8s que vous acc\u00e9dez \u00e0 ce site web.<\/p>\n<h4>\u00c0 quelles fins utilisons-nous vos donn\u00e9es ?<\/h4>\n<p>Une partie des donn\u00e9es est collect\u00e9e afin de garantir une mise \u00e0 disposition sans erreur du site web. D&#8217;autres donn\u00e9es peuvent \u00eatre utilis\u00e9es pour analyser votre comportement d&#8217;utilisateur.<\/p>\n<h4>Quels sont vos droits concernant vos donn\u00e9es ?<\/h4>\n<p>Vous avez \u00e0 tout moment le droit d&#8217;obtenir gratuitement des informations sur l&#8217;origine, le destinataire et la finalit\u00e9 de vos donn\u00e9es personnelles enregistr\u00e9es. Vous avez \u00e9galement le droit d&#8217;exiger la rectification ou la suppression de ces donn\u00e9es. Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, vous pouvez \u00e0 tout moment r\u00e9voquer ce consentement pour l&#8217;avenir. Vous avez \u00e9galement le droit de demander la limitation du traitement de vos donn\u00e9es personnelles dans certaines circonstances. En outre, vous disposez d&#8217;un droit de recours aupr\u00e8s de l&#8217;autorit\u00e9 de surveillance comp\u00e9tente.<\/p>\n<p>Vous pouvez nous contacter \u00e0 tout moment \u00e0 ce sujet ou pour toute autre question relative \u00e0 la protection des donn\u00e9es.<\/p>\n<h2>2. Hosting<\/h2>\n<p>Nous h\u00e9bergeons le contenu de notre site web chez le fournisseur suivant :<\/p>\n<p>\u00bb OFFICE KOMPLETT Computer Service GmbH<br \/>\u00bb mail@officekomplett.com<\/p>\n<h3>Hosting externe<\/h3>\n<p>Ce site web est h\u00e9berg\u00e9 en externe. Les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es sur ce site sont stock\u00e9es sur les serveurs de l&#8217;h\u00e9bergeur\/des h\u00e9bergeurs. Il peut s&#8217;agir notamment d&#8217;adresses IP, de demandes de contact, de m\u00e9tadonn\u00e9es et de donn\u00e9es de communication, de donn\u00e9es contractuelles, de donn\u00e9es de contact, de noms, de visites de sites web et d&#8217;autres donn\u00e9es g\u00e9n\u00e9r\u00e9es par un site web.<\/p>\n<p>L&#8217;hosting externe est effectu\u00e9 aux fins de l&#8217;ex\u00e9cution du contrat vis-\u00e0-vis de nos clients potentiels et existants (art. 6, paragraphe 1, point b du RGPD) et dans l&#8217;int\u00e9r\u00eat d&#8217;une mise \u00e0 disposition s\u00fbre, rapide et efficace de notre offre en ligne par un fournisseur professionnel (art. 6, paragraphe 1, point f du RGPD). Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s&#8217;effectue exclusivement sur la base de l&#8217;article 6, paragraphe 1, point a), du RGPD et de l&#8217;article 25, paragraphe 1, de la loi sur la protection des donn\u00e9es (TTDSG), dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l&#8217;acc\u00e8s \u00e0 des informations dans le terminal de l&#8217;utilisateur (par ex. Device-Fingerprinting) au sens de la TTDSG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n<p>Notre(nos) h\u00e9bergeur(s) ne traitera(ont) vos donn\u00e9es que dans la mesure o\u00f9 cela est n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution de ses obligations de service et se conformera(ront) \u00e0 nos instructions concernant ces donn\u00e9es.<\/p>\n<p>Nous utilisons le ou les h\u00e9bergeurs suivants :<\/p>\n<p>TelemaxX Telekommunikation GmbH<br \/>Amalienbadstra\u00dfe 41,<br \/>76227 Karlsruhe<\/p>\n<h2>3. Remarques g\u00e9n\u00e9rales et informations obligatoires<\/h2>\n<h3>Protection des donn\u00e9es<\/h3>\n<p>Les exploitants de ces pages prennent la protection de vos donn\u00e9es personnelles tr\u00e8s au s\u00e9rieux. Nous traitons vos donn\u00e9es personnelles de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales en mati\u00e8re de protection des donn\u00e9es ainsi qu&#8217;\u00e0 la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<p>Lorsque vous utilisez ce site web, diverses donn\u00e9es personnelles sont collect\u00e9es. Les donn\u00e9es personnelles sont des donn\u00e9es qui permettent de vous identifier personnellement. La pr\u00e9sente d\u00e9claration de confidentialit\u00e9 explique quelles donn\u00e9es nous collectons et \u00e0 quelles fins nous les utilisons. Elle explique \u00e9galement comment et dans quel but nous le faisons.<\/p>\n<p>Nous attirons votre attention sur le fait que la transmission de donn\u00e9es sur Internet (par ex. lors de la communication par e-mail) peut pr\u00e9senter des failles de s\u00e9curit\u00e9. Une protection compl\u00e8te des donn\u00e9es contre l&#8217;acc\u00e8s par des tiers n&#8217;est pas possible.<\/p>\n<h3>Remarque sur le service responsable<\/h3>\n<p>Le responsable du traitement des donn\u00e9es sur ce site est :<\/p>\n<p>Frank R\u00fcde GmbH<br \/>Luttinger Stra\u00dfe 78<br \/>79725 Laufenburg<\/p>\n<p>R\u00fcde GmbH, Kunststoffverarbeitung<br \/>Lippersmatt 3<br \/>79725 Laufenburg<\/p>\n<p>Spritz-Plast GmbH<br \/>Luttinger Stra\u00dfe 72<br \/>79725 Laufenburg<\/p>\n<p>Telefon: +49 7763 &#8211; 927 95-0<br \/>E-Mail: info@ruede.de<\/p>\n<p>Le responsable du traitement est la personne physique ou morale qui, seule ou conjointement avec d&#8217;autres, d\u00e9termine les finalit\u00e9s et les moyens du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel (par exemple, les noms, les adresses \u00e9lectroniques ou autres).<\/p>\n<h3>Dur\u00e9e de stockage<\/h3>\n<p>Dans la mesure o\u00f9 aucune dur\u00e9e de stockage sp\u00e9cifique n&#8217;a \u00e9t\u00e9 mentionn\u00e9e dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es, vos donn\u00e9es \u00e0 caract\u00e8re personnel restent chez nous jusqu&#8217;\u00e0 ce que la finalit\u00e9 du traitement des donn\u00e9es n&#8217;ait plus lieu d&#8217;\u00eatre. Si vous faites valoir une demande l\u00e9gitime d&#8217;effacement ou si vous r\u00e9voquez votre consentement au traitement des donn\u00e9es, vos donn\u00e9es seront effac\u00e9es, \u00e0 moins que nous n&#8217;ayons d&#8217;autres raisons l\u00e9galement valables de conserver vos donn\u00e9es personnelles (par exemple, des d\u00e9lais de conservation en vertu du droit fiscal ou commercial) ; dans ce dernier cas, l&#8217;effacement aura lieu apr\u00e8s la disparition de ces raisons.<\/p>\n<h3>Informations g\u00e9n\u00e9rales sur les bases juridiques du traitement des donn\u00e9es sur ce site web<\/h3>\n<p>Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, nous traitons vos donn\u00e9es personnelles sur la base de l&#8217;article 6, paragraphe 1, point a) du RGPD ou de l&#8217;article 9, paragraphe 2, point a) du RGPD, dans la mesure o\u00f9 des cat\u00e9gories particuli\u00e8res de donn\u00e9es sont trait\u00e9es conform\u00e9ment \u00e0 l&#8217;article 9, paragraphe 1 du RGPD. En cas de consentement explicite au transfert de donn\u00e9es \u00e0 caract\u00e8re personnel vers des pays tiers, le traitement des donn\u00e9es s&#8217;effectue en outre sur la base de l&#8217;article 49, paragraphe 1, point a) du RGPD. Si vous avez consenti \u00e0 l&#8217;enregistrement de cookies ou \u00e0 l&#8217;acc\u00e8s \u00e0 des informations dans votre terminal (par exemple via l&#8217;empreinte digitale de l&#8217;appareil), le traitement des donn\u00e9es s&#8217;effectue en outre sur la base de l&#8217;article 25, paragraphe 1, de la TTDSG. Ce consentement est r\u00e9vocable \u00e0 tout moment. Si vos donn\u00e9es sont n\u00e9cessaires \u00e0 l&#8217;ex\u00e9cution d&#8217;un contrat ou \u00e0 la mise en \u0153uvre de mesures pr\u00e9contractuelles, nous traitons vos donn\u00e9es sur la base de l&#8217;article 6, paragraphe 1, point b), du RGPD. En outre, nous traitons vos donn\u00e9es si elles sont n\u00e9cessaires pour remplir une obligation l\u00e9gale sur la base de l&#8217;article 6, paragraphe 1, point c) du RGPD. Le traitement des donn\u00e9es peut \u00e9galement \u00eatre effectu\u00e9 sur la base de notre int\u00e9r\u00eat l\u00e9gitime conform\u00e9ment \u00e0 l&#8217;article 6, paragraphe 1, point f), du RGPD. Les paragraphes suivants de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es informent sur les bases juridiques applicables dans chaque cas.<\/p>\n<h3>Destinataires des donn\u00e9es \u00e0 caract\u00e8re personnel<\/h3>\n<p>Dans le cadre de nos activit\u00e9s commerciales, nous collaborons avec diff\u00e9rents services externes. Dans ce cadre, il est parfois n\u00e9cessaire de transmettre des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 ces organismes externes. Nous ne transmettons des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 des organismes externes que si cela est n\u00e9cessaire dans le cadre de l&#8217;ex\u00e9cution d&#8217;un contrat, si nous y sommes contraints par la loi (par ex. transmission de donn\u00e9es aux autorit\u00e9s fiscales), si nous avons un int\u00e9r\u00eat l\u00e9gitime \u00e0 la transmission conform\u00e9ment \u00e0 l&#8217;article 6, paragraphe 1, point f), du RGPD ou si une autre base juridique permet la transmission des donn\u00e9es. En cas de recours \u00e0 des sous-traitants, nous ne transmettons les donn\u00e9es \u00e0 caract\u00e8re personnel de nos clients que sur la base d&#8217;un contrat de traitement des commandes valable. En cas de traitement conjoint, un contrat de traitement conjoint est conclu.<\/p>\n<h3>R\u00e9vocation de votre consentement au traitement des donn\u00e9es<\/h3>\n<p>De nombreuses op\u00e9rations de traitement des donn\u00e9es ne sont possibles qu&#8217;avec votre consentement explicite. Vous pouvez r\u00e9voquer \u00e0 tout moment un consentement d\u00e9j\u00e0 donn\u00e9. La l\u00e9galit\u00e9 du traitement des donn\u00e9es effectu\u00e9 jusqu&#8217;\u00e0 la r\u00e9vocation n&#8217;est pas affect\u00e9e par la r\u00e9vocation.<\/p>\n<h3>Droit d&#8217;opposition \u00e0 la collecte de donn\u00e9es dans des cas particuliers ainsi qu&#8217;\u00e0 la publicit\u00e9 directe (art. 21 RGPD)<\/h3>\n<p>LORSQUE LE TRAITEMENT DES DONN\u00c9ES EST EFFECTU\u00c9 SUR LA BASE DE L&#8217;ART. 6 ABS. 1 LIT. E OU F DU RGPD, VOUS AVEZ LE DROIT DE VOUS OPPOSER \u00c0 TOUT MOMENT, POUR DES RAISONS TENANT \u00c0 VOTRE SITUATION PARTICULI\u00c8RE, AU TRAITEMENT DE VOS DONN\u00c9ES PERSONNELLES ; CECI S&#8217;APPLIQUE \u00c9GALEMENT AU PROFILAGE FOND\u00c9 SUR CES DISPOSITIONS. VOUS TROUVEREZ DANS LA PR\u00c9SENTE D\u00c9CLARATION DE PROTECTION DES DONN\u00c9ES LES BASES JURIDIQUES RESPECTIVES SUR LESQUELLES SE FONDE UN TRAITEMENT. SI VOUS VOUS Y OPPOSEZ, NOUS NE TRAITERONS PLUS VOS DONN\u00c9ES PERSONNELLES CONCERN\u00c9ES, \u00c0 MOINS QUE NOUS NE PUISSIONS D\u00c9MONTRER DES MOTIFS IMP\u00c9RIEUX ET L\u00c9GITIMES POUR LE TRAITEMENT QUI PR\u00c9VALENT SUR VOS INT\u00c9R\u00caTS, VOS DROITS ET VOS LIBERT\u00c9S, OU QUE LE TRAITEMENT SERVE \u00c0 FAIRE VALOIR, \u00c0 EXERCER OU \u00c0 D\u00c9FENDRE DES DROITS EN JUSTICE (OPPOSITION \u00c0 L&#8217;ARTICLE 21, PARAGRAPHE 1, DU RGPD).<\/p>\n<p>SI VOS DONN\u00c9ES PERSONNELLES SONT TRAIT\u00c9ES \u00c0 DES FINS DE PUBLICIT\u00c9 DIRECTE, VOUS AVEZ LE DROIT DE VOUS OPPOSER \u00c0 TOUT MOMENT AU TRAITEMENT DES DONN\u00c9ES PERSONNELLES VOUS CONCERNANT \u00c0 DES FINS DE PUBLICIT\u00c9 DIRECTE ; CECI S&#8217;APPLIQUE \u00c9GALEMENT AU PROFILAGE DANS LA MESURE O\u00d9 IL EST LI\u00c9 \u00c0 UNE TELLE PUBLICIT\u00c9 DIRECTE. SI VOUS VOUS Y OPPOSEZ, VOS DONN\u00c9ES PERSONNELLES NE SERONT PLUS UTILIS\u00c9ES \u00c0 DES FINS DE PUBLICIT\u00c9 DIRECTE (OPPOSITION CONFORM\u00c9MENT \u00c0 L&#8217;ARTICLE 21, PARAGRAPHE 2, DU TRAIT\u00c9 D&#8217;AMSTERDAM).<\/p>\n<h3>Droit de recours aupr\u00e8s de l&#8217;autorit\u00e9 de surveillance comp\u00e9tente\u00a0<\/h3>\n<p>En cas de violation du RGPD, les personnes concern\u00e9es disposent d&#8217;un droit de recours aupr\u00e8s d&#8217;une autorit\u00e9 de contr\u00f4le, en particulier dans l&#8217;\u00c9tat membre de leur r\u00e9sidence habituelle, de leur lieu de travail ou du lieu de la violation pr\u00e9sum\u00e9e. Ce droit de recours s&#8217;exerce sans pr\u00e9judice des autres voies de recours administratives ou judiciaires.<\/p>\n<h3>Droit \u00e0 la portabilit\u00e9 des donn\u00e9es<\/h3>\n<p>Vous avez le droit de vous faire remettre ou de faire remettre \u00e0 un tiers, dans un format courant et lisible par machine, les donn\u00e9es que nous traitons de mani\u00e8re automatis\u00e9e sur la base de votre consentement ou en ex\u00e9cution d&#8217;un contrat. Si vous demandez la transmission directe des donn\u00e9es \u00e0 un autre responsable, cela ne se fera que dans la mesure o\u00f9 cela est techniquement possible.<\/p>\n<h3>Acc\u00e8s, rectification et suppression<\/h3>\n<p>Dans le cadre des dispositions l\u00e9gales en vigueur, vous avez \u00e0 tout moment le droit d&#8217;obtenir gratuitement des informations sur vos donn\u00e9es personnelles enregistr\u00e9es, leur origine et leur destinataire ainsi que sur la finalit\u00e9 du traitement des donn\u00e9es et, le cas \u00e9ch\u00e9ant, un droit de rectification ou de suppression de ces donn\u00e9es. Pour ce faire, ainsi que pour toute autre question relative aux donn\u00e9es personnelles, vous pouvez nous contacter \u00e0 tout moment.<\/p>\n<h3>Droit \u00e0 la limitation du traitement<\/h3>\n<p>Vous avez le droit de demander la limitation du traitement de vos donn\u00e9es personnelles. Pour ce faire, vous pouvez nous contacter \u00e0 tout moment. Le droit \u00e0 la limitation du traitement existe dans les cas suivants :<\/p>\n<ul>\n<li>Si vous contestez l&#8217;exactitude de vos donn\u00e9es \u00e0 caract\u00e8re personnel enregistr\u00e9es chez nous, nous avons g\u00e9n\u00e9ralement besoin de temps pour le v\u00e9rifier. Pendant la dur\u00e9e de la v\u00e9rification, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.<\/li>\n<li>Si le traitement de vos donn\u00e9es personnelles s&#8217;est produit\/se produit de mani\u00e8re ill\u00e9gale, vous pouvez demander la limitation du traitement des donn\u00e9es au lieu de leur suppression.<\/li>\n<li>Si nous n&#8217;avons plus besoin de vos donn\u00e9es \u00e0 caract\u00e8re personnel, mais que vous en avez besoin pour exercer, d\u00e9fendre ou faire valoir des droits juridiques, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel au lieu de leur suppression.<\/li>\n<li>Si vous avez fait opposition conform\u00e9ment \u00e0 l&#8217;article 21, paragraphe 1, du RGPD, une mise en balance de vos int\u00e9r\u00eats et des n\u00f4tres doit \u00eatre effectu\u00e9e. Tant qu&#8217;il n&#8217;a pas \u00e9t\u00e9 d\u00e9termin\u00e9 quels int\u00e9r\u00eats pr\u00e9valent, vous avez le droit d&#8217;exiger la limitation du traitement de vos donn\u00e9es personnelles.<\/li>\n<\/ul>\n<p>Si vous avez limit\u00e9 le traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel, ces donn\u00e9es &#8211; \u00e0 l&#8217;exception de leur conservation &#8211; ne peuvent \u00eatre trait\u00e9es qu&#8217;avec votre consentement ou pour la constatation, l&#8217;exercice ou la d\u00e9fense de droits en justice ou pour la protection des droits d&#8217;une autre personne physique ou morale, ou encore pour un motif d&#8217;int\u00e9r\u00eat public important de l&#8217;Union europ\u00e9enne ou d&#8217;un \u00c9tat membre.<\/p>\n<h3>Chiffrement SSL ou TLS<\/h3>\n<p>Pour des raisons de s\u00e9curit\u00e9 et afin de prot\u00e9ger la transmission de contenus confidentiels, comme par exemple les commandes ou les demandes que vous nous envoyez en tant qu&#8217;exploitant du site, ce site utilise un cryptage SSL ou TLS. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d&#8217;adresse du navigateur passe de &#8220;http:\/\/&#8221; \u00e0 &#8220;https:\/\/&#8221; et au symbole du cadenas dans la ligne de votre navigateur.<\/p>\n<p>Si le cryptage SSL ou TLS est activ\u00e9, les donn\u00e9es que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<h3>Opposition aux e-mails publicitaires<\/h3>\n<p>L&#8217;utilisation des donn\u00e9es de contact publi\u00e9es dans le cadre des mentions l\u00e9gales obligatoires pour l&#8217;envoi de publicit\u00e9 et de mat\u00e9riel d&#8217;information non express\u00e9ment demand\u00e9s est interdite. Les exploitants des pages se r\u00e9servent express\u00e9ment le droit d&#8217;engager des poursuites judiciaires en cas d&#8217;envoi non sollicit\u00e9 d&#8217;informations publicitaires, par exemple par le biais de spams.<\/p>\n<h2>4. Collecte de donn\u00e9es sur ce site web<\/h2>\n<h3>Cookies<\/h3>\n<p>Nos pages Internet utilisent ce que l&#8217;on appelle des &#8220;cookies&#8221;. Les cookies sont de petits paquets de donn\u00e9es qui ne causent aucun dommage \u00e0 votre terminal. Ils sont enregistr\u00e9s sur votre terminal soit temporairement pour la dur\u00e9e d&#8217;une session (cookies de session), soit durablement (cookies permanents). Les cookies de session sont automatiquement supprim\u00e9s \u00e0 la fin de votre visite. Les cookies permanents restent enregistr\u00e9s sur votre terminal jusqu&#8217;\u00e0 ce que vous les supprimiez vous-m\u00eame ou qu&#8217;une suppression automatique soit effectu\u00e9e par votre navigateur web.<\/p>\n<p>Les cookies peuvent provenir de nous (cookies de premi\u00e8re partie) ou d&#8217;entreprises tierces (cookies dits de troisi\u00e8me partie). Les cookies tiers permettent d&#8217;int\u00e9grer certains services d&#8217;entreprises tierces au sein des pages web (par exemple, des cookies pour le traitement des services de paiement).<\/p>\n<p>Les cookies ont diff\u00e9rentes fonctions. De nombreux cookies sont techniquement n\u00e9cessaires, car certaines fonctions du site web ne fonctionneraient pas sans eux (par exemple la fonction de panier d&#8217;achat ou l&#8217;affichage de vid\u00e9os). D&#8217;autres cookies peuvent \u00eatre utilis\u00e9s pour \u00e9valuer le comportement des utilisateurs ou \u00e0 des fins publicitaires.<\/p>\n<p>Les cookies n\u00e9cessaires \u00e0 l&#8217;ex\u00e9cution du processus de communication \u00e9lectronique, \u00e0 la mise \u00e0 disposition de certaines fonctions que vous souhaitez (par ex. pour la fonction de panier d&#8217;achat) ou \u00e0 l&#8217;optimisation du site web (par ex. cookies de mesure d&#8217;audience web) (cookies n\u00e9cessaires) sont enregistr\u00e9s sur la base de l&#8217;article 6, paragraphe 1, point f du RGPD, sauf si une autre base juridique est indiqu\u00e9e. L&#8217;exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 l&#8217;enregistrement des cookies n\u00e9cessaires pour une mise \u00e0 disposition de ses services sans erreur technique et optimis\u00e9e. Si un consentement a \u00e9t\u00e9 demand\u00e9 pour l&#8217;enregistrement de cookies et de technologies de reconnaissance comparables, le traitement est effectu\u00e9 exclusivement sur la base de ce consentement (art. 6, al. 1, let. a RGPD et \u00a7 25, al. 1 TTDSG) ; le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n<p>Vous pouvez configurer votre navigateur de mani\u00e8re \u00e0 \u00eatre inform\u00e9 de l&#8217;installation de cookies et \u00e0 n&#8217;autoriser les cookies qu&#8217;au cas par cas, \u00e0 exclure l&#8217;acceptation de cookies dans certains cas ou de mani\u00e8re g\u00e9n\u00e9rale, et \u00e0 activer la suppression automatique des cookies \u00e0 la fermeture du navigateur. En cas de d\u00e9sactivation des cookies, la fonctionnalit\u00e9 de ce site web peut \u00eatre limit\u00e9e.<\/p>\n<p>Pour savoir quels cookies et services sont utilis\u00e9s sur ce site, veuillez consulter la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n<h3>Formulaire de contact<\/h3>\n<p>Si vous nous faites parvenir des demandes par le biais du formulaire de contact, les informations que vous avez fournies dans le formulaire de demande, y compris les donn\u00e9es de contact que vous y avez indiqu\u00e9es, sont enregistr\u00e9es chez nous \u00e0 des fins de traitement de la demande et en cas de questions de suivi. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<\/p>\n<p>Le traitement de ces donn\u00e9es est fond\u00e9 sur l&#8217;article 6, paragraphe 1, point b), du RGPD, dans la mesure o\u00f9 votre demande est li\u00e9e \u00e0 l&#8217;ex\u00e9cution d&#8217;un contrat ou est n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution de mesures pr\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 traiter efficacement les demandes qui nous sont adress\u00e9es (article 6, paragraphe 1, point f) du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a) du RGPD) dans la mesure o\u00f9 celui-ci a \u00e9t\u00e9 demand\u00e9 ; le consentement peut \u00eatre retir\u00e9 \u00e0 tout moment.<\/p>\n<p>Les donn\u00e9es que vous avez saisies dans le formulaire de contact restent chez nous jusqu&#8217;\u00e0 ce que vous nous demandiez de les supprimer, que vous r\u00e9voquiez votre autorisation de les enregistrer ou que le but de l&#8217;enregistrement des donn\u00e9es devienne caduc (par ex. apr\u00e8s le traitement de votre demande). Les dispositions l\u00e9gales contraignantes &#8211; en particulier les d\u00e9lais de conservation &#8211; ne sont pas affect\u00e9es.<\/p>\n<h3>Demande par e-mail, t\u00e9l\u00e9phone ou fax<\/h3>\n<p>Si vous nous contactez par e-mail, t\u00e9l\u00e9phone ou fax, votre demande, y compris toutes les donn\u00e9es personnelles qui en d\u00e9coulent (nom, demande), sera enregistr\u00e9e et trait\u00e9e par nos soins dans le but de traiter votre demande. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<\/p>\n<p>Le traitement de ces donn\u00e9es est fond\u00e9 sur l&#8217;article 6, paragraphe 1, point b), du RGPD, dans la mesure o\u00f9 votre demande est li\u00e9e \u00e0 l&#8217;ex\u00e9cution d&#8217;un contrat ou est n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution de mesures pr\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 traiter efficacement les demandes qui nous sont adress\u00e9es (article 6, paragraphe 1, point f) du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a) du RGPD) dans la mesure o\u00f9 celui-ci a \u00e9t\u00e9 demand\u00e9 ; le consentement peut \u00eatre retir\u00e9 \u00e0 tout moment.<\/p>\n<p>Les donn\u00e9es que vous nous avez envoy\u00e9es par le biais de demandes de contact restent chez nous jusqu&#8217;\u00e0 ce que vous nous demandiez de les effacer, que vous r\u00e9voquiez votre consentement \u00e0 leur stockage ou que le but du stockage des donn\u00e9es devienne caduc (par exemple apr\u00e8s le traitement de votre demande). Les dispositions l\u00e9gales contraignantes &#8211; en particulier les d\u00e9lais de conservation l\u00e9gaux &#8211; ne sont pas affect\u00e9es.<\/p>\n<h2>5. Commerce \u00e9lectronique et fournisseurs de paiement<\/h2>\n<h3>Traitement des donn\u00e9es clients et des donn\u00e9es contractuelles<\/h3>\n<p>Nous collectons, traitons et utilisons les donn\u00e9es personnelles des clients et les donn\u00e9es contractuelles pour justifier, d\u00e9finir le contenu et modifier nos relations contractuelles. Nous ne collectons, traitons et utilisons les donn\u00e9es personnelles relatives \u00e0 l&#8217;utilisation de ce site web (donn\u00e9es d&#8217;utilisation) que dans la mesure o\u00f9 cela est n\u00e9cessaire pour permettre \u00e0 l&#8217;utilisateur d&#8217;utiliser le service ou de le facturer. L&#8217;article 6, paragraphe 1, point b) du RGPD constitue la base juridique de ces donn\u00e9es.<\/p>\n<p>Les donn\u00e9es clients collect\u00e9es sont supprim\u00e9es apr\u00e8s l&#8217;ach\u00e8vement de la commande ou la fin de la relation commerciale et l&#8217;expiration des d\u00e9lais de conservation l\u00e9gaux \u00e9ventuellement existants. Les d\u00e9lais de conservation l\u00e9gaux ne sont pas affect\u00e9s.<\/p>\n<h2>6. Propres services<\/h2>\n<h3>Traitement des donn\u00e9es des candidats<\/h3>\n<p>Nous vous offrons la possibilit\u00e9 de postuler chez nous (par ex. par e-mail, par courrier ou via le formulaire de candidature en ligne). Nous vous informons ci-apr\u00e8s de l&#8217;\u00e9tendue, de la finalit\u00e9 et de l&#8217;utilisation de vos donn\u00e9es personnelles collect\u00e9es dans le cadre du processus de candidature. Nous vous assurons que la collecte, le traitement et l&#8217;utilisation de vos donn\u00e9es sont conformes \u00e0 la l\u00e9gislation en vigueur sur la protection des donn\u00e9es et \u00e0 toutes les autres dispositions l\u00e9gales et que vos donn\u00e9es sont trait\u00e9es de mani\u00e8re strictement confidentielle.<\/p>\n<h4>Port\u00e9e et objectif de la collecte de donn\u00e9es<\/h4>\n<p>Lorsque vous nous envoyez une candidature, nous traitons les donn\u00e9es personnelles qui y sont li\u00e9es (par ex. donn\u00e9es de contact et de communication, dossier de candidature, notes prises dans le cadre d&#8217;entretiens d&#8217;embauche, etc.), dans la mesure o\u00f9 cela est n\u00e9cessaire pour d\u00e9cider de l&#8217;\u00e9tablissement d&#8217;une relation de travail. La base juridique est l&#8217;article 26 BDSG selon le droit allemand (initiation d&#8217;une relation d&#8217;emploi), l&#8217;article 6, paragraphe 1, point b) RGPD (initiation g\u00e9n\u00e9rale d&#8217;un contrat) et &#8211; si vous avez donn\u00e9 votre consentement &#8211; l&#8217;article 6, paragraphe 1, point a) RGPD. Le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment. Au sein de notre entreprise, vos donn\u00e9es personnelles ne sont transmises qu&#8217;aux personnes impliqu\u00e9es dans le traitement de votre candidature.<\/p>\n<p>Si la candidature est retenue, les donn\u00e9es que vous avez soumises sont enregistr\u00e9es dans nos syst\u00e8mes de traitement des donn\u00e9es sur la base de l&#8217;article 26 de la loi f\u00e9d\u00e9rale sur la protection des donn\u00e9es (BDSG) et de l&#8217;article 6, paragraphe 1, point b), du RGPD, aux fins de l&#8217;ex\u00e9cution de la relation d&#8217;emploi.<\/p>\n<h4>Dur\u00e9e de conservation des donn\u00e9es<\/h4>\n<p>Si nous ne sommes pas en mesure de vous proposer un emploi, si vous refusez une offre d&#8217;emploi ou si vous retirez votre candidature, nous nous r\u00e9servons le droit de conserver chez nous les donn\u00e9es que vous nous avez transmises, sur la base de nos int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, point f) du RGPD), pendant une dur\u00e9e maximale de six mois \u00e0 compter de la fin de la proc\u00e9dure de candidature (refus ou retrait de la candidature). Ensuite, les donn\u00e9es sont effac\u00e9es et les dossiers de candidature physiques sont d\u00e9truits. La conservation sert notamment \u00e0 des fins de preuve en cas de litige. S&#8217;il est \u00e9vident que les donn\u00e9es seront n\u00e9cessaires apr\u00e8s l&#8217;expiration du d\u00e9lai de six mois (par exemple en raison d&#8217;une menace de litige ou d&#8217;un litige en cours), elles ne seront supprim\u00e9es que lorsque la finalit\u00e9 de leur conservation ult\u00e9rieure n&#8217;aura plus lieu d&#8217;\u00eatre.\u00a0<\/p>\n<p>Une conservation plus longue peut en outre avoir lieu si vous avez donn\u00e9 votre consentement (article 6, paragraphe 1, point a) du RGPD) ou si des obligations l\u00e9gales de conservation s&#8217;opposent \u00e0 l&#8217;effacement.<\/p>\n<h4>Int\u00e9gration dans le pool de candidats<\/h4>\n<p>Si nous ne vous proposons pas d&#8217;offre d&#8217;emploi, il est possible de vous int\u00e9grer dans notre pool de candidats. En cas d&#8217;admission, tous les documents et donn\u00e9es de la candidature sont repris dans le pool de candidats afin de vous contacter en cas de poste vacant correspondant.<\/p>\n<p>L&#8217;int\u00e9gration dans le pool de candidats se fait exclusivement sur la base de votre consentement explicite (article 6, paragraphe 1, point a du RGPD). La remise du consentement est volontaire et n&#8217;a aucun rapport avec la proc\u00e9dure de candidature en cours. La personne concern\u00e9e peut r\u00e9voquer son consentement \u00e0 tout moment. Dans ce cas, les donn\u00e9es seront irr\u00e9vocablement supprim\u00e9es du pool de candidats, sauf si des raisons l\u00e9gales de conservation existent.\u00a0<\/p>\n<p>Les donn\u00e9es du pool de candidats sont irr\u00e9vocablement supprim\u00e9es au plus tard deux ans apr\u00e8s l&#8217;octroi du consentement.<\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<h1>D\\u00e9claration de confidentialit\\u00e9<\\\/h1>\\n\n\n<h2>1.Aper\\u00e7u de la protection des donn\\u00e9es<\\\/h2>\\n\n\n<h3>Remarques g\\u00e9n\\u00e9rales<\\\/h3>\\n\n\n<p>Les indications suivantes donnent un aper\\u00e7u simple de ce qui se passe avec vos donn\\u00e9es personnelles lorsque vous visitez ce site web. Les donn\\u00e9es personnelles sont toutes les donn\\u00e9es qui permettent de vous identifier personnellement. Vous trouverez des informations d\\u00e9taill\\u00e9es sur le th\\u00e8me de la protection des donn\\u00e9es dans notre d\\u00e9claration de protection des donn\\u00e9es figurant sous ce texte.<\\\/p>\\n\n\n<h3>Collecte de donn\\u00e9es sur ce site web<\\\/h3>\\n\n\n<h4>Qui est responsable de la collecte des donn\\u00e9es sur ce site ?<\\\/h4>\\n\n\n<p>Le traitement des donn\\u00e9es sur ce site web est effectu\\u00e9 par l'exploitant du site web. Vous trouverez les coordonn\\u00e9es de ce dernier dans la section \\\"Informations sur le responsable du traitement\\\" de la pr\\u00e9sente d\\u00e9claration de protection des donn\\u00e9es.<\\\/p>\\n\n\n<h4>Comment recueillons-nous vos donn\\u00e9es ?<\\\/h4>\\n\n\n<p>Vos donn\\u00e9es sont collect\\u00e9es, d'une part, lorsque vous nous les communiquez. Il peut s'agir, par exemple, de donn\\u00e9es que vous saisissez dans un formulaire de contact.<\\\/p>\\n\n\n<p>D'autres donn\\u00e9es sont collect\\u00e9es automatiquement ou apr\\u00e8s votre accord par nos syst\\u00e8mes informatiques lorsque vous visitez le site web. Il s'agit principalement de donn\\u00e9es techniques (par exemple, le navigateur Internet, le syst\\u00e8me d'exploitation ou l'heure de consultation de la page). La saisie de ces donn\\u00e9es s'effectue automatiquement d\\u00e8s que vous acc\\u00e9dez \\u00e0 ce site web.<\\\/p>\\n\n\n<h4>\\u00c0 quelles fins utilisons-nous vos donn\\u00e9es ?<\\\/h4>\\n\n\n<p>Une partie des donn\\u00e9es est collect\\u00e9e afin de garantir une mise \\u00e0 disposition sans erreur du site web. D'autres donn\\u00e9es peuvent \\u00eatre utilis\\u00e9es pour analyser votre comportement d'utilisateur.<\\\/p>\\n\n\n<h4>Quels sont vos droits concernant vos donn\\u00e9es ?<\\\/h4>\\n\n\n<p>Vous avez \\u00e0 tout moment le droit d'obtenir gratuitement des informations sur l'origine, le destinataire et la finalit\\u00e9 de vos donn\\u00e9es personnelles enregistr\\u00e9es. Vous avez \\u00e9galement le droit d'exiger la rectification ou la suppression de ces donn\\u00e9es. Si vous avez donn\\u00e9 votre consentement au traitement des donn\\u00e9es, vous pouvez \\u00e0 tout moment r\\u00e9voquer ce consentement pour l'avenir. Vous avez \\u00e9galement le droit de demander la limitation du traitement de vos donn\\u00e9es personnelles dans certaines circonstances. En outre, vous disposez d'un droit de recours aupr\\u00e8s de l'autorit\\u00e9 de surveillance comp\\u00e9tente.<\\\/p>\\n\n\n<p>Vous pouvez nous contacter \\u00e0 tout moment \\u00e0 ce sujet ou pour toute autre question relative \\u00e0 la protection des donn\\u00e9es.<\\\/p>\\n\n\n<h2>2. Hosting<\\\/h2>\\n\n\n<p>Nous h\\u00e9bergeons le contenu de notre site web chez le fournisseur suivant :<\\\/p>\\n\n\n<p>\\u00bb OFFICE KOMPLETT Computer Service GmbH<br \\\/>\\u00bb mail@officekomplett.com<\\\/p>\\n\n\n<h3>Hosting externe<\\\/h3>\\n\n\n<p>Ce site web est h\\u00e9berg\\u00e9 en externe. Les donn\\u00e9es \\u00e0 caract\\u00e8re personnel collect\\u00e9es sur ce site sont stock\\u00e9es sur les serveurs de l'h\\u00e9bergeur\\\/des h\\u00e9bergeurs. Il peut s'agir notamment d'adresses IP, de demandes de contact, de m\\u00e9tadonn\\u00e9es et de donn\\u00e9es de communication, de donn\\u00e9es contractuelles, de donn\\u00e9es de contact, de noms, de visites de sites web et d'autres donn\\u00e9es g\\u00e9n\\u00e9r\\u00e9es par un site web.<\\\/p>\\n\n\n<p>L'hosting externe est effectu\\u00e9 aux fins de l'ex\\u00e9cution du contrat vis-\\u00e0-vis de nos clients potentiels et existants (art. 6, paragraphe 1, point b du RGPD) et dans l'int\\u00e9r\\u00eat d'une mise \\u00e0 disposition s\\u00fbre, rapide et efficace de notre offre en ligne par un fournisseur professionnel (art. 6, paragraphe 1, point f du RGPD). Dans la mesure o\\u00f9 un consentement correspondant a \\u00e9t\\u00e9 demand\\u00e9, le traitement s'effectue exclusivement sur la base de l'article 6, paragraphe 1, point a), du RGPD et de l'article 25, paragraphe 1, de la loi sur la protection des donn\\u00e9es (TTDSG), dans la mesure o\\u00f9 le consentement inclut le stockage de cookies ou l'acc\\u00e8s \\u00e0 des informations dans le terminal de l'utilisateur (par ex. Device-Fingerprinting) au sens de la TTDSG. Le consentement est r\\u00e9vocable \\u00e0 tout moment.<\\\/p>\\n\n\n<p>Notre(nos) h\\u00e9bergeur(s) ne traitera(ont) vos donn\\u00e9es que dans la mesure o\\u00f9 cela est n\\u00e9cessaire \\u00e0 l'ex\\u00e9cution de ses obligations de service et se conformera(ront) \\u00e0 nos instructions concernant ces donn\\u00e9es.<\\\/p>\\n\n\n<p>Nous utilisons le ou les h\\u00e9bergeurs suivants :<\\\/p>\\n\n\n<p>TelemaxX Telekommunikation GmbH<br \\\/>Amalienbadstra\\u00dfe 41,<br \\\/>76227 Karlsruhe<\\\/p>\\n\n\n<h2>3. Remarques g\\u00e9n\\u00e9rales et informations obligatoires<\\\/h2>\\n\n\n<h3>Protection des donn\\u00e9es<\\\/h3>\\n\n\n<p>Les exploitants de ces pages prennent la protection de vos donn\\u00e9es personnelles tr\\u00e8s au s\\u00e9rieux. Nous traitons vos donn\\u00e9es personnelles de mani\\u00e8re confidentielle et conform\\u00e9ment aux dispositions l\\u00e9gales en mati\\u00e8re de protection des donn\\u00e9es ainsi qu'\\u00e0 la pr\\u00e9sente d\\u00e9claration de protection des donn\\u00e9es.<\\\/p>\\n\n\n<p>Lorsque vous utilisez ce site web, diverses donn\\u00e9es personnelles sont collect\\u00e9es. Les donn\\u00e9es personnelles sont des donn\\u00e9es qui permettent de vous identifier personnellement. La pr\\u00e9sente d\\u00e9claration de confidentialit\\u00e9 explique quelles donn\\u00e9es nous collectons et \\u00e0 quelles fins nous les utilisons. Elle explique \\u00e9galement comment et dans quel but nous le faisons.<\\\/p>\\n\n\n<p>Nous attirons votre attention sur le fait que la transmission de donn\\u00e9es sur Internet (par ex. lors de la communication par e-mail) peut pr\\u00e9senter des failles de s\\u00e9curit\\u00e9. Une protection compl\\u00e8te des donn\\u00e9es contre l'acc\\u00e8s par des tiers n'est pas possible.<\\\/p>\\n\n\n<h3>Remarque sur le service responsable<\\\/h3>\\n\n\n<p>Le responsable du traitement des donn\\u00e9es sur ce site est :<\\\/p>\\n\n\n<p>Frank R\\u00fcde GmbH<br \\\/>Luttinger Stra\\u00dfe 78<br \\\/>79725 Laufenburg<br \\\/><br \\\/>R\\u00fcde GmbH, Kunststoffverarbeitung<br \\\/>Lippersmatt 3<br \\\/>79725 Laufenburg<br \\\/><br \\\/>Spritz-Plast GmbH<br \\\/>Luttinger Stra\\u00dfe 72<br \\\/>79725 Laufenburg<\\\/p>\\n\n\n<p>Telefon: +49 7763 - 927 95-0<br \\\/>E-Mail: info@ruede.de<\\\/p>\\n\n\n<p>Le responsable du traitement est la personne physique ou morale qui, seule ou conjointement avec d'autres, d\\u00e9termine les finalit\\u00e9s et les moyens du traitement des donn\\u00e9es \\u00e0 caract\\u00e8re personnel (par exemple, les noms, les adresses \\u00e9lectroniques ou autres).<\\\/p>\\n\n\n<h3>Dur\\u00e9e de stockage<\\\/h3>\\n\n\n<p>Dans la mesure o\\u00f9 aucune dur\\u00e9e de stockage sp\\u00e9cifique n'a \\u00e9t\\u00e9 mentionn\\u00e9e dans la pr\\u00e9sente d\\u00e9claration de protection des donn\\u00e9es, vos donn\\u00e9es \\u00e0 caract\\u00e8re personnel restent chez nous jusqu'\\u00e0 ce que la finalit\\u00e9 du traitement des donn\\u00e9es n'ait plus lieu d'\\u00eatre. Si vous faites valoir une demande l\\u00e9gitime d'effacement ou si vous r\\u00e9voquez votre consentement au traitement des donn\\u00e9es, vos donn\\u00e9es seront effac\\u00e9es, \\u00e0 moins que nous n'ayons d'autres raisons l\\u00e9galement valables de conserver vos donn\\u00e9es personnelles (par exemple, des d\\u00e9lais de conservation en vertu du droit fiscal ou commercial) ; dans ce dernier cas, l'effacement aura lieu apr\\u00e8s la disparition de ces raisons.<\\\/p>\\n\n\n<h3>Informations g\\u00e9n\\u00e9rales sur les bases juridiques du traitement des donn\\u00e9es sur ce site web<\\\/h3>\\n\n\n<p>Si vous avez donn\\u00e9 votre consentement au traitement des donn\\u00e9es, nous traitons vos donn\\u00e9es personnelles sur la base de l'article 6, paragraphe 1, point a) du RGPD ou de l'article 9, paragraphe 2, point a) du RGPD, dans la mesure o\\u00f9 des cat\\u00e9gories particuli\\u00e8res de donn\\u00e9es sont trait\\u00e9es conform\\u00e9ment \\u00e0 l'article 9, paragraphe 1 du RGPD. En cas de consentement explicite au transfert de donn\\u00e9es \\u00e0 caract\\u00e8re personnel vers des pays tiers, le traitement des donn\\u00e9es s'effectue en outre sur la base de l'article 49, paragraphe 1, point a) du RGPD. Si vous avez consenti \\u00e0 l'enregistrement de cookies ou \\u00e0 l'acc\\u00e8s \\u00e0 des informations dans votre terminal (par exemple via l'empreinte digitale de l'appareil), le traitement des donn\\u00e9es s'effectue en outre sur la base de l'article 25, paragraphe 1, de la TTDSG. Ce consentement est r\\u00e9vocable \\u00e0 tout moment. Si vos donn\\u00e9es sont n\\u00e9cessaires \\u00e0 l'ex\\u00e9cution d'un contrat ou \\u00e0 la mise en \\u0153uvre de mesures pr\\u00e9contractuelles, nous traitons vos donn\\u00e9es sur la base de l'article 6, paragraphe 1, point b), du RGPD. En outre, nous traitons vos donn\\u00e9es si elles sont n\\u00e9cessaires pour remplir une obligation l\\u00e9gale sur la base de l'article 6, paragraphe 1, point c) du RGPD. Le traitement des donn\\u00e9es peut \\u00e9galement \\u00eatre effectu\\u00e9 sur la base de notre int\\u00e9r\\u00eat l\\u00e9gitime conform\\u00e9ment \\u00e0 l'article 6, paragraphe 1, point f), du RGPD. Les paragraphes suivants de la pr\\u00e9sente d\\u00e9claration de protection des donn\\u00e9es informent sur les bases juridiques applicables dans chaque cas.<\\\/p>\\n\n\n<h3>Destinataires des donn\\u00e9es \\u00e0 caract\\u00e8re personnel<\\\/h3>\\n\n\n<p>Dans le cadre de nos activit\\u00e9s commerciales, nous collaborons avec diff\\u00e9rents services externes. Dans ce cadre, il est parfois n\\u00e9cessaire de transmettre des donn\\u00e9es \\u00e0 caract\\u00e8re personnel \\u00e0 ces organismes externes. Nous ne transmettons des donn\\u00e9es \\u00e0 caract\\u00e8re personnel \\u00e0 des organismes externes que si cela est n\\u00e9cessaire dans le cadre de l'ex\\u00e9cution d'un contrat, si nous y sommes contraints par la loi (par ex. transmission de donn\\u00e9es aux autorit\\u00e9s fiscales), si nous avons un int\\u00e9r\\u00eat l\\u00e9gitime \\u00e0 la transmission conform\\u00e9ment \\u00e0 l'article 6, paragraphe 1, point f), du RGPD ou si une autre base juridique permet la transmission des donn\\u00e9es. En cas de recours \\u00e0 des sous-traitants, nous ne transmettons les donn\\u00e9es \\u00e0 caract\\u00e8re personnel de nos clients que sur la base d'un contrat de traitement des commandes valable. En cas de traitement conjoint, un contrat de traitement conjoint est conclu.<\\\/p>\\n\n\n<h3>R\\u00e9vocation de votre consentement au traitement des donn\\u00e9es<\\\/h3>\\n\n\n<p>De nombreuses op\\u00e9rations de traitement des donn\\u00e9es ne sont possibles qu'avec votre consentement explicite. Vous pouvez r\\u00e9voquer \\u00e0 tout moment un consentement d\\u00e9j\\u00e0 donn\\u00e9. La l\\u00e9galit\\u00e9 du traitement des donn\\u00e9es effectu\\u00e9 jusqu'\\u00e0 la r\\u00e9vocation n'est pas affect\\u00e9e par la r\\u00e9vocation.<\\\/p>\\n\n\n<h3>Droit d'opposition \\u00e0 la collecte de donn\\u00e9es dans des cas particuliers ainsi qu'\\u00e0 la publicit\\u00e9 directe (art. 21 RGPD)<\\\/h3>\\n\n\n<p>LORSQUE LE TRAITEMENT DES DONN\\u00c9ES EST EFFECTU\\u00c9 SUR LA BASE DE L'ART. 6 ABS. 1 LIT. E OU F DU RGPD, VOUS AVEZ LE DROIT DE VOUS OPPOSER \\u00c0 TOUT MOMENT, POUR DES RAISONS TENANT \\u00c0 VOTRE SITUATION PARTICULI\\u00c8RE, AU TRAITEMENT DE VOS DONN\\u00c9ES PERSONNELLES ; CECI S'APPLIQUE \\u00c9GALEMENT AU PROFILAGE FOND\\u00c9 SUR CES DISPOSITIONS. VOUS TROUVEREZ DANS LA PR\\u00c9SENTE D\\u00c9CLARATION DE PROTECTION DES DONN\\u00c9ES LES BASES JURIDIQUES RESPECTIVES SUR LESQUELLES SE FONDE UN TRAITEMENT. SI VOUS VOUS Y OPPOSEZ, NOUS NE TRAITERONS PLUS VOS DONN\\u00c9ES PERSONNELLES CONCERN\\u00c9ES, \\u00c0 MOINS QUE NOUS NE PUISSIONS D\\u00c9MONTRER DES MOTIFS IMP\\u00c9RIEUX ET L\\u00c9GITIMES POUR LE TRAITEMENT QUI PR\\u00c9VALENT SUR VOS INT\\u00c9R\\u00caTS, VOS DROITS ET VOS LIBERT\\u00c9S, OU QUE LE TRAITEMENT SERVE \\u00c0 FAIRE VALOIR, \\u00c0 EXERCER OU \\u00c0 D\\u00c9FENDRE DES DROITS EN JUSTICE (OPPOSITION \\u00c0 L'ARTICLE 21, PARAGRAPHE 1, DU RGPD).<\\\/p>\\n\n\n<p>SI VOS DONN\\u00c9ES PERSONNELLES SONT TRAIT\\u00c9ES \\u00c0 DES FINS DE PUBLICIT\\u00c9 DIRECTE, VOUS AVEZ LE DROIT DE VOUS OPPOSER \\u00c0 TOUT MOMENT AU TRAITEMENT DES DONN\\u00c9ES PERSONNELLES VOUS CONCERNANT \\u00c0 DES FINS DE PUBLICIT\\u00c9 DIRECTE ; CECI S'APPLIQUE \\u00c9GALEMENT AU PROFILAGE DANS LA MESURE O\\u00d9 IL EST LI\\u00c9 \\u00c0 UNE TELLE PUBLICIT\\u00c9 DIRECTE. SI VOUS VOUS Y OPPOSEZ, VOS DONN\\u00c9ES PERSONNELLES NE SERONT PLUS UTILIS\\u00c9ES \\u00c0 DES FINS DE PUBLICIT\\u00c9 DIRECTE (OPPOSITION CONFORM\\u00c9MENT \\u00c0 L'ARTICLE 21, PARAGRAPHE 2, DU TRAIT\\u00c9 D'AMSTERDAM).<\\\/p>\\n\n\n<h3>Droit de recours aupr\\u00e8s de l'autorit\\u00e9 de surveillance comp\\u00e9tente\\u00a0<\\\/h3>\\n\n\n<p>En cas de violation du RGPD, les personnes concern\\u00e9es disposent d'un droit de recours aupr\\u00e8s d'une autorit\\u00e9 de contr\\u00f4le, en particulier dans l'\\u00c9tat membre de leur r\\u00e9sidence habituelle, de leur lieu de travail ou du lieu de la violation pr\\u00e9sum\\u00e9e. Ce droit de recours s'exerce sans pr\\u00e9judice des autres voies de recours administratives ou judiciaires.<\\\/p>\\n\n\n<h3>Droit \\u00e0 la portabilit\\u00e9 des donn\\u00e9es<\\\/h3>\\n\n\n<p>Vous avez le droit de vous faire remettre ou de faire remettre \\u00e0 un tiers, dans un format courant et lisible par machine, les donn\\u00e9es que nous traitons de mani\\u00e8re automatis\\u00e9e sur la base de votre consentement ou en ex\\u00e9cution d'un contrat. Si vous demandez la transmission directe des donn\\u00e9es \\u00e0 un autre responsable, cela ne se fera que dans la mesure o\\u00f9 cela est techniquement possible.<\\\/p>\\n\n\n<h3>Acc\\u00e8s, rectification et suppression<\\\/h3>\\n\n\n<p>Dans le cadre des dispositions l\\u00e9gales en vigueur, vous avez \\u00e0 tout moment le droit d'obtenir gratuitement des informations sur vos donn\\u00e9es personnelles enregistr\\u00e9es, leur origine et leur destinataire ainsi que sur la finalit\\u00e9 du traitement des donn\\u00e9es et, le cas \\u00e9ch\\u00e9ant, un droit de rectification ou de suppression de ces donn\\u00e9es. Pour ce faire, ainsi que pour toute autre question relative aux donn\\u00e9es personnelles, vous pouvez nous contacter \\u00e0 tout moment.<\\\/p>\\n\n\n<h3>Droit \\u00e0 la limitation du traitement<\\\/h3>\\n\n\n<p>Vous avez le droit de demander la limitation du traitement de vos donn\\u00e9es personnelles. Pour ce faire, vous pouvez nous contacter \\u00e0 tout moment. Le droit \\u00e0 la limitation du traitement existe dans les cas suivants :<\\\/p>\\n\n\n<ul>\\n\n\n<li>Si vous contestez l'exactitude de vos donn\\u00e9es \\u00e0 caract\\u00e8re personnel enregistr\\u00e9es chez nous, nous avons g\\u00e9n\\u00e9ralement besoin de temps pour le v\\u00e9rifier. Pendant la dur\\u00e9e de la v\\u00e9rification, vous avez le droit de demander la limitation du traitement de vos donn\\u00e9es \\u00e0 caract\\u00e8re personnel.<\\\/li>\\n\n\n<li>Si le traitement de vos donn\\u00e9es personnelles s'est produit\\\/se produit de mani\\u00e8re ill\\u00e9gale, vous pouvez demander la limitation du traitement des donn\\u00e9es au lieu de leur suppression.<\\\/li>\\n\n\n<li>Si nous n'avons plus besoin de vos donn\\u00e9es \\u00e0 caract\\u00e8re personnel, mais que vous en avez besoin pour exercer, d\\u00e9fendre ou faire valoir des droits juridiques, vous avez le droit de demander la limitation du traitement de vos donn\\u00e9es \\u00e0 caract\\u00e8re personnel au lieu de leur suppression.<\\\/li>\\n\n\n<li>Si vous avez fait opposition conform\\u00e9ment \\u00e0 l'article 21, paragraphe 1, du RGPD, une mise en balance de vos int\\u00e9r\\u00eats et des n\\u00f4tres doit \\u00eatre effectu\\u00e9e. Tant qu'il n'a pas \\u00e9t\\u00e9 d\\u00e9termin\\u00e9 quels int\\u00e9r\\u00eats pr\\u00e9valent, vous avez le droit d'exiger la limitation du traitement de vos donn\\u00e9es personnelles.<\\\/li>\\n<\\\/ul>\\n\n\n<p>Si vous avez limit\\u00e9 le traitement de vos donn\\u00e9es \\u00e0 caract\\u00e8re personnel, ces donn\\u00e9es - \\u00e0 l'exception de leur conservation - ne peuvent \\u00eatre trait\\u00e9es qu'avec votre consentement ou pour la constatation, l'exercice ou la d\\u00e9fense de droits en justice ou pour la protection des droits d'une autre personne physique ou morale, ou encore pour un motif d'int\\u00e9r\\u00eat public important de l'Union europ\\u00e9enne ou d'un \\u00c9tat membre.<\\\/p>\\n\n\n<h3>Chiffrement SSL ou TLS<\\\/h3>\\n\n\n<p>Pour des raisons de s\\u00e9curit\\u00e9 et afin de prot\\u00e9ger la transmission de contenus confidentiels, comme par exemple les commandes ou les demandes que vous nous envoyez en tant qu'exploitant du site, ce site utilise un cryptage SSL ou TLS. Vous reconnaissez une connexion crypt\\u00e9e au fait que la ligne d'adresse du navigateur passe de \\\"http:\\\/\\\/\\\" \\u00e0 \\\"https:\\\/\\\/\\\" et au symbole du cadenas dans la ligne de votre navigateur.<\\\/p>\\n\n\n<p>Si le cryptage SSL ou TLS est activ\\u00e9, les donn\\u00e9es que vous nous transmettez ne peuvent pas \\u00eatre lues par des tiers.<\\\/p>\\n\n\n<h3>Opposition aux e-mails publicitaires<\\\/h3>\\n\n\n<p>L'utilisation des donn\\u00e9es de contact publi\\u00e9es dans le cadre des mentions l\\u00e9gales obligatoires pour l'envoi de publicit\\u00e9 et de mat\\u00e9riel d'information non express\\u00e9ment demand\\u00e9s est interdite. Les exploitants des pages se r\\u00e9servent express\\u00e9ment le droit d'engager des poursuites judiciaires en cas d'envoi non sollicit\\u00e9 d'informations publicitaires, par exemple par le biais de spams.<\\\/p>\\n\n\n<h2>4. Collecte de donn\\u00e9es sur ce site web<\\\/h2>\\n\n\n<h3>Cookies<\\\/h3>\\n\n\n<p>Nos pages Internet utilisent ce que l'on appelle des \\\"cookies\\\". Les cookies sont de petits paquets de donn\\u00e9es qui ne causent aucun dommage \\u00e0 votre terminal. Ils sont enregistr\\u00e9s sur votre terminal soit temporairement pour la dur\\u00e9e d'une session (cookies de session), soit durablement (cookies permanents). Les cookies de session sont automatiquement supprim\\u00e9s \\u00e0 la fin de votre visite. Les cookies permanents restent enregistr\\u00e9s sur votre terminal jusqu'\\u00e0 ce que vous les supprimiez vous-m\\u00eame ou qu'une suppression automatique soit effectu\\u00e9e par votre navigateur web.<\\\/p>\\n\n\n<p>Les cookies peuvent provenir de nous (cookies de premi\\u00e8re partie) ou d'entreprises tierces (cookies dits de troisi\\u00e8me partie). Les cookies tiers permettent d'int\\u00e9grer certains services d'entreprises tierces au sein des pages web (par exemple, des cookies pour le traitement des services de paiement).<\\\/p>\\n\n\n<p>Les cookies ont diff\\u00e9rentes fonctions. De nombreux cookies sont techniquement n\\u00e9cessaires, car certaines fonctions du site web ne fonctionneraient pas sans eux (par exemple la fonction de panier d'achat ou l'affichage de vid\\u00e9os). D'autres cookies peuvent \\u00eatre utilis\\u00e9s pour \\u00e9valuer le comportement des utilisateurs ou \\u00e0 des fins publicitaires.<\\\/p>\\n\n\n<p>Les cookies n\\u00e9cessaires \\u00e0 l'ex\\u00e9cution du processus de communication \\u00e9lectronique, \\u00e0 la mise \\u00e0 disposition de certaines fonctions que vous souhaitez (par ex. pour la fonction de panier d'achat) ou \\u00e0 l'optimisation du site web (par ex. cookies de mesure d'audience web) (cookies n\\u00e9cessaires) sont enregistr\\u00e9s sur la base de l'article 6, paragraphe 1, point f du RGPD, sauf si une autre base juridique est indiqu\\u00e9e. L'exploitant du site web a un int\\u00e9r\\u00eat l\\u00e9gitime \\u00e0 l'enregistrement des cookies n\\u00e9cessaires pour une mise \\u00e0 disposition de ses services sans erreur technique et optimis\\u00e9e. Si un consentement a \\u00e9t\\u00e9 demand\\u00e9 pour l'enregistrement de cookies et de technologies de reconnaissance comparables, le traitement est effectu\\u00e9 exclusivement sur la base de ce consentement (art. 6, al. 1, let. a RGPD et \\u00a7 25, al. 1 TTDSG) ; le consentement peut \\u00eatre r\\u00e9voqu\\u00e9 \\u00e0 tout moment.<\\\/p>\\n\n\n<p>Vous pouvez configurer votre navigateur de mani\\u00e8re \\u00e0 \\u00eatre inform\\u00e9 de l'installation de cookies et \\u00e0 n'autoriser les cookies qu'au cas par cas, \\u00e0 exclure l'acceptation de cookies dans certains cas ou de mani\\u00e8re g\\u00e9n\\u00e9rale, et \\u00e0 activer la suppression automatique des cookies \\u00e0 la fermeture du navigateur. En cas de d\\u00e9sactivation des cookies, la fonctionnalit\\u00e9 de ce site web peut \\u00eatre limit\\u00e9e.<\\\/p>\\n\n\n<p>Pour savoir quels cookies et services sont utilis\\u00e9s sur ce site, veuillez consulter la pr\\u00e9sente d\\u00e9claration de confidentialit\\u00e9.<\\\/p>\\n\n\n<h3>Formulaire de contact<\\\/h3>\\n\n\n<p>Si vous nous faites parvenir des demandes par le biais du formulaire de contact, les informations que vous avez fournies dans le formulaire de demande, y compris les donn\\u00e9es de contact que vous y avez indiqu\\u00e9es, sont enregistr\\u00e9es chez nous \\u00e0 des fins de traitement de la demande et en cas de questions de suivi. Nous ne transmettons pas ces donn\\u00e9es sans votre consentement.<\\\/p>\\n\n\n<p>Le traitement de ces donn\\u00e9es est fond\\u00e9 sur l'article 6, paragraphe 1, point b), du RGPD, dans la mesure o\\u00f9 votre demande est li\\u00e9e \\u00e0 l'ex\\u00e9cution d'un contrat ou est n\\u00e9cessaire \\u00e0 l'ex\\u00e9cution de mesures pr\\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\\u00e9r\\u00eat l\\u00e9gitime \\u00e0 traiter efficacement les demandes qui nous sont adress\\u00e9es (article 6, paragraphe 1, point f) du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a) du RGPD) dans la mesure o\\u00f9 celui-ci a \\u00e9t\\u00e9 demand\\u00e9 ; le consentement peut \\u00eatre retir\\u00e9 \\u00e0 tout moment.<\\\/p>\\n\n\n<p>Les donn\\u00e9es que vous avez saisies dans le formulaire de contact restent chez nous jusqu'\\u00e0 ce que vous nous demandiez de les supprimer, que vous r\\u00e9voquiez votre autorisation de les enregistrer ou que le but de l'enregistrement des donn\\u00e9es devienne caduc (par ex. apr\\u00e8s le traitement de votre demande). Les dispositions l\\u00e9gales contraignantes - en particulier les d\\u00e9lais de conservation - ne sont pas affect\\u00e9es.<\\\/p>\\n\n\n<h3>Demande par e-mail, t\\u00e9l\\u00e9phone ou fax<\\\/h3>\\n\n\n<p>Si vous nous contactez par e-mail, t\\u00e9l\\u00e9phone ou fax, votre demande, y compris toutes les donn\\u00e9es personnelles qui en d\\u00e9coulent (nom, demande), sera enregistr\\u00e9e et trait\\u00e9e par nos soins dans le but de traiter votre demande. Nous ne transmettons pas ces donn\\u00e9es sans votre consentement.<\\\/p>\\n\n\n<p>Le traitement de ces donn\\u00e9es est fond\\u00e9 sur l'article 6, paragraphe 1, point b), du RGPD, dans la mesure o\\u00f9 votre demande est li\\u00e9e \\u00e0 l'ex\\u00e9cution d'un contrat ou est n\\u00e9cessaire \\u00e0 l'ex\\u00e9cution de mesures pr\\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\\u00e9r\\u00eat l\\u00e9gitime \\u00e0 traiter efficacement les demandes qui nous sont adress\\u00e9es (article 6, paragraphe 1, point f) du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a) du RGPD) dans la mesure o\\u00f9 celui-ci a \\u00e9t\\u00e9 demand\\u00e9 ; le consentement peut \\u00eatre retir\\u00e9 \\u00e0 tout moment.<\\\/p>\\n\n\n<p>Les donn\\u00e9es que vous nous avez envoy\\u00e9es par le biais de demandes de contact restent chez nous jusqu'\\u00e0 ce que vous nous demandiez de les effacer, que vous r\\u00e9voquiez votre consentement \\u00e0 leur stockage ou que le but du stockage des donn\\u00e9es devienne caduc (par exemple apr\\u00e8s le traitement de votre demande). Les dispositions l\\u00e9gales contraignantes - en particulier les d\\u00e9lais de conservation l\\u00e9gaux - ne sont pas affect\\u00e9es.<\\\/p>\\n\n\n<h2>5. Commerce \\u00e9lectronique et fournisseurs de paiement<\\\/h2>\\n\n\n<h3>Traitement des donn\\u00e9es clients et des donn\\u00e9es contractuelles<\\\/h3>\\n\n\n<p>Nous collectons, traitons et utilisons les donn\\u00e9es personnelles des clients et les donn\\u00e9es contractuelles pour justifier, d\\u00e9finir le contenu et modifier nos relations contractuelles. Nous ne collectons, traitons et utilisons les donn\\u00e9es personnelles relatives \\u00e0 l'utilisation de ce site web (donn\\u00e9es d'utilisation) que dans la mesure o\\u00f9 cela est n\\u00e9cessaire pour permettre \\u00e0 l'utilisateur d'utiliser le service ou de le facturer. L'article 6, paragraphe 1, point b) du RGPD constitue la base juridique de ces donn\\u00e9es.<\\\/p>\\n\n\n<p>Les donn\\u00e9es clients collect\\u00e9es sont supprim\\u00e9es apr\\u00e8s l'ach\\u00e8vement de la commande ou la fin de la relation commerciale et l'expiration des d\\u00e9lais de conservation l\\u00e9gaux \\u00e9ventuellement existants. Les d\\u00e9lais de conservation l\\u00e9gaux ne sont pas affect\\u00e9s.<\\\/p>\\n\n\n<h2>6. Propres services<\\\/h2>\\n\n\n<h3>Traitement des donn\\u00e9es des candidats<\\\/h3>\\n\n\n<p>Nous vous offrons la possibilit\\u00e9 de postuler chez nous (par ex. par e-mail, par courrier ou via le formulaire de candidature en ligne). Nous vous informons ci-apr\\u00e8s de l'\\u00e9tendue, de la finalit\\u00e9 et de l'utilisation de vos donn\\u00e9es personnelles collect\\u00e9es dans le cadre du processus de candidature. Nous vous assurons que la collecte, le traitement et l'utilisation de vos donn\\u00e9es sont conformes \\u00e0 la l\\u00e9gislation en vigueur sur la protection des donn\\u00e9es et \\u00e0 toutes les autres dispositions l\\u00e9gales et que vos donn\\u00e9es sont trait\\u00e9es de mani\\u00e8re strictement confidentielle.<\\\/p>\\n\n\n<h4>Port\\u00e9e et objectif de la collecte de donn\\u00e9es<\\\/h4>\\n\n\n<p>Lorsque vous nous envoyez une candidature, nous traitons les donn\\u00e9es personnelles qui y sont li\\u00e9es (par ex. donn\\u00e9es de contact et de communication, dossier de candidature, notes prises dans le cadre d'entretiens d'embauche, etc.), dans la mesure o\\u00f9 cela est n\\u00e9cessaire pour d\\u00e9cider de l'\\u00e9tablissement d'une relation de travail. La base juridique est l'article 26 BDSG selon le droit allemand (initiation d'une relation d'emploi), l'article 6, paragraphe 1, point b) RGPD (initiation g\\u00e9n\\u00e9rale d'un contrat) et - si vous avez donn\\u00e9 votre consentement - l'article 6, paragraphe 1, point a) RGPD. Le consentement peut \\u00eatre r\\u00e9voqu\\u00e9 \\u00e0 tout moment. Au sein de notre entreprise, vos donn\\u00e9es personnelles ne sont transmises qu'aux personnes impliqu\\u00e9es dans le traitement de votre candidature.<\\\/p>\\n\n\n<p>Si la candidature est retenue, les donn\\u00e9es que vous avez soumises sont enregistr\\u00e9es dans nos syst\\u00e8mes de traitement des donn\\u00e9es sur la base de l'article 26 de la loi f\\u00e9d\\u00e9rale sur la protection des donn\\u00e9es (BDSG) et de l'article 6, paragraphe 1, point b), du RGPD, aux fins de l'ex\\u00e9cution de la relation d'emploi.<\\\/p>\\n\n\n<h4>Dur\\u00e9e de conservation des donn\\u00e9es<\\\/h4>\\n\n\n<p>Si nous ne sommes pas en mesure de vous proposer un emploi, si vous refusez une offre d'emploi ou si vous retirez votre candidature, nous nous r\\u00e9servons le droit de conserver chez nous les donn\\u00e9es que vous nous avez transmises, sur la base de nos int\\u00e9r\\u00eats l\\u00e9gitimes (article 6, paragraphe 1, point f) du RGPD), pendant une dur\\u00e9e maximale de six mois \\u00e0 compter de la fin de la proc\\u00e9dure de candidature (refus ou retrait de la candidature). Ensuite, les donn\\u00e9es sont effac\\u00e9es et les dossiers de candidature physiques sont d\\u00e9truits. La conservation sert notamment \\u00e0 des fins de preuve en cas de litige. S'il est \\u00e9vident que les donn\\u00e9es seront n\\u00e9cessaires apr\\u00e8s l'expiration du d\\u00e9lai de six mois (par exemple en raison d'une menace de litige ou d'un litige en cours), elles ne seront supprim\\u00e9es que lorsque la finalit\\u00e9 de leur conservation ult\\u00e9rieure n'aura plus lieu d'\\u00eatre.\\u00a0<\\\/p>\\n\n\n<p>Une conservation plus longue peut en outre avoir lieu si vous avez donn\\u00e9 votre consentement (article 6, paragraphe 1, point a) du RGPD) ou si des obligations l\\u00e9gales de conservation s'opposent \\u00e0 l'effacement.<\\\/p>\\n\n\n<h4>Int\\u00e9gration dans le pool de candidats<\\\/h4>\\n\n\n<p>Si nous ne vous proposons pas d'offre d'emploi, il est possible de vous int\\u00e9grer dans notre pool de candidats. En cas d'admission, tous les documents et donn\\u00e9es de la candidature sont repris dans le pool de candidats afin de vous contacter en cas de poste vacant correspondant.<\\\/p>\\n\n\n<p>L'int\\u00e9gration dans le pool de candidats se fait exclusivement sur la base de votre consentement explicite (article 6, paragraphe 1, point a du RGPD). La remise du consentement est volontaire et n'a aucun rapport avec la proc\\u00e9dure de candidature en cours. La personne concern\\u00e9e peut r\\u00e9voquer son consentement \\u00e0 tout moment. Dans ce cas, les donn\\u00e9es seront irr\\u00e9vocablement supprim\\u00e9es du pool de candidats, sauf si des raisons l\\u00e9gales de conservation existent.\\u00a0<\\\/p>\\n\n\n<p>Les donn\\u00e9es du pool de candidats sont irr\\u00e9vocablement supprim\\u00e9es au plus tard deux ans apr\\u00e8s l'octroi du consentement.<\\\/p>\",\"margin\":\"default\"}}]}]}]}],\"version\":\"4.1.5\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9claration de confidentialit\u00e9 1.Aper\u00e7u de la protection des donn\u00e9es Remarques g\u00e9n\u00e9rales Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement. Vous trouverez des informations d\u00e9taill\u00e9es sur le th\u00e8me de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6973","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcde Gruppe: Datenschutz<\/title>\n<meta name=\"description\" content=\"Die Verarbeitung Ihrer personenbezogenen Daten erfolgt unter Beachtung der geltenden Datenschutzbestimmungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcde Gruppe: Datenschutz\" \/>\n<meta property=\"og:description\" content=\"Die Verarbeitung Ihrer personenbezogenen Daten erfolgt unter Beachtung der geltenden Datenschutzbestimmungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00fcde Gruppe\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T13:28:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/protection-des-donnees\\\/\",\"url\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/protection-des-donnees\\\/\",\"name\":\"R\u00fcde Gruppe: Datenschutz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#website\"},\"datePublished\":\"2023-07-19T05:25:22+00:00\",\"dateModified\":\"2024-06-18T13:28:42+00:00\",\"description\":\"Die Verarbeitung Ihrer personenbezogenen Daten erfolgt unter Beachtung der geltenden Datenschutzbestimmungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/protection-des-donnees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ruede.de\\\/fr\\\/protection-des-donnees\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/protection-des-donnees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection des donn\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/\",\"name\":\"R\u00fcde Gruppe\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcde Gruppe: Datenschutz","description":"Die Verarbeitung Ihrer personenbezogenen Daten erfolgt unter Beachtung der geltenden Datenschutzbestimmungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00fcde Gruppe: Datenschutz","og_description":"Die Verarbeitung Ihrer personenbezogenen Daten erfolgt unter Beachtung der geltenden Datenschutzbestimmungen.","og_url":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/","og_site_name":"R\u00fcde Gruppe","article_modified_time":"2024-06-18T13:28:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/","url":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/","name":"R\u00fcde Gruppe: Datenschutz","isPartOf":{"@id":"https:\/\/www.ruede.de\/fr\/#website"},"datePublished":"2023-07-19T05:25:22+00:00","dateModified":"2024-06-18T13:28:42+00:00","description":"Die Verarbeitung Ihrer personenbezogenen Daten erfolgt unter Beachtung der geltenden Datenschutzbestimmungen.","breadcrumb":{"@id":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ruede.de\/fr\/protection-des-donnees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ruede.de\/fr\/protection-des-donnees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ruede.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Protection des donn\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.ruede.de\/fr\/#website","url":"https:\/\/www.ruede.de\/fr\/","name":"R\u00fcde Gruppe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ruede.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/pages\/6973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/comments?post=6973"}],"version-history":[{"count":21,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/pages\/6973\/revisions"}],"predecessor-version":[{"id":18057,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/pages\/6973\/revisions\/18057"}],"wp:attachment":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/media?parent=6973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}