{"id":27734,"date":"2024-07-19T09:11:05","date_gmt":"2024-07-19T07:11:05","guid":{"rendered":"https:\/\/www.ruede.de\/kunststoff-verschlussstopfen\/"},"modified":"2024-07-25T15:41:50","modified_gmt":"2024-07-25T13:41:50","slug":"bouchons-en-plastique","status":"publish","type":"post","link":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/","title":{"rendered":"Bouchons en plastique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.<\/p>\n","protected":false},"author":7,"featured_media":23454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-27734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bouchons en plastique - R\u00fcde Gruppe<\/title>\n<meta name=\"description\" content=\"Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bouchons en plastique - R\u00fcde Gruppe\" \/>\n<meta property=\"og:description\" content=\"Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00fcde Gruppe\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-19T07:11:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T13:41:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ruede.de\/wp-content\/uploads\/2024\/07\/407.v-Kunststoff-Verschlussstopfen-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yakup Yilmaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yakup Yilmaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/\"},\"author\":{\"name\":\"Yakup Yilmaz\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#\\\/schema\\\/person\\\/93cdf4d23884fa0ef3f14e24cb120636\"},\"headline\":\"Bouchons en plastique\",\"datePublished\":\"2024-07-19T07:11:05+00:00\",\"dateModified\":\"2024-07-25T13:41:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ruede.de\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/407.v-Kunststoff-Verschlussstopfen-3.png\",\"articleSection\":[\"Produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/\",\"url\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/\",\"name\":\"Bouchons en plastique - R\u00fcde Gruppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ruede.de\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/407.v-Kunststoff-Verschlussstopfen-3.png\",\"datePublished\":\"2024-07-19T07:11:05+00:00\",\"dateModified\":\"2024-07-25T13:41:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#\\\/schema\\\/person\\\/93cdf4d23884fa0ef3f14e24cb120636\"},\"description\":\"Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ruede.de\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/407.v-Kunststoff-Verschlussstopfen-3.png\",\"contentUrl\":\"https:\\\/\\\/www.ruede.de\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/407.v-Kunststoff-Verschlussstopfen-3.png\",\"width\":1023,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/bouchons-en-plastique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bouchons en plastique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/\",\"name\":\"R\u00fcde Gruppe\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ruede.de\\\/fr\\\/#\\\/schema\\\/person\\\/93cdf4d23884fa0ef3f14e24cb120636\",\"name\":\"Yakup Yilmaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbe99bfb93bb62fd186f9fff6d1372affad161d99523e00adcc6c314d43c1e7b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbe99bfb93bb62fd186f9fff6d1372affad161d99523e00adcc6c314d43c1e7b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbe99bfb93bb62fd186f9fff6d1372affad161d99523e00adcc6c314d43c1e7b?s=96&d=mm&r=g\",\"caption\":\"Yakup Yilmaz\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bouchons en plastique - R\u00fcde Gruppe","description":"Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/","og_locale":"fr_FR","og_type":"article","og_title":"Bouchons en plastique - R\u00fcde Gruppe","og_description":"Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.","og_url":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/","og_site_name":"R\u00fcde Gruppe","article_published_time":"2024-07-19T07:11:05+00:00","article_modified_time":"2024-07-25T13:41:50+00:00","og_image":[{"width":1023,"height":682,"url":"https:\/\/www.ruede.de\/wp-content\/uploads\/2024\/07\/407.v-Kunststoff-Verschlussstopfen-3.png","type":"image\/png"}],"author":"Yakup Yilmaz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Yakup Yilmaz","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#article","isPartOf":{"@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/"},"author":{"name":"Yakup Yilmaz","@id":"https:\/\/www.ruede.de\/fr\/#\/schema\/person\/93cdf4d23884fa0ef3f14e24cb120636"},"headline":"Bouchons en plastique","datePublished":"2024-07-19T07:11:05+00:00","dateModified":"2024-07-25T13:41:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/"},"wordCount":33,"image":{"@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ruede.de\/wp-content\/uploads\/2024\/07\/407.v-Kunststoff-Verschlussstopfen-3.png","articleSection":["Produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/","url":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/","name":"Bouchons en plastique - R\u00fcde Gruppe","isPartOf":{"@id":"https:\/\/www.ruede.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#primaryimage"},"image":{"@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ruede.de\/wp-content\/uploads\/2024\/07\/407.v-Kunststoff-Verschlussstopfen-3.png","datePublished":"2024-07-19T07:11:05+00:00","dateModified":"2024-07-25T13:41:50+00:00","author":{"@id":"https:\/\/www.ruede.de\/fr\/#\/schema\/person\/93cdf4d23884fa0ef3f14e24cb120636"},"description":"Les bouchons (rondelles) de fermeture servent \u00e0 fermer les cavit\u00e9s des chevilles de montage dans les \u00e9l\u00e9ments de construction afin de cr\u00e9er une surface propre et esth\u00e9tique.","breadcrumb":{"@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#primaryimage","url":"https:\/\/www.ruede.de\/wp-content\/uploads\/2024\/07\/407.v-Kunststoff-Verschlussstopfen-3.png","contentUrl":"https:\/\/www.ruede.de\/wp-content\/uploads\/2024\/07\/407.v-Kunststoff-Verschlussstopfen-3.png","width":1023,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.ruede.de\/fr\/bouchons-en-plastique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ruede.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Bouchons en plastique"}]},{"@type":"WebSite","@id":"https:\/\/www.ruede.de\/fr\/#website","url":"https:\/\/www.ruede.de\/fr\/","name":"R\u00fcde Gruppe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ruede.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ruede.de\/fr\/#\/schema\/person\/93cdf4d23884fa0ef3f14e24cb120636","name":"Yakup Yilmaz","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bbe99bfb93bb62fd186f9fff6d1372affad161d99523e00adcc6c314d43c1e7b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bbe99bfb93bb62fd186f9fff6d1372affad161d99523e00adcc6c314d43c1e7b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbe99bfb93bb62fd186f9fff6d1372affad161d99523e00adcc6c314d43c1e7b?s=96&d=mm&r=g","caption":"Yakup Yilmaz"}}]}},"_links":{"self":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/posts\/27734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/comments?post=27734"}],"version-history":[{"count":4,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/posts\/27734\/revisions"}],"predecessor-version":[{"id":27741,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/posts\/27734\/revisions\/27741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/media\/23454"}],"wp:attachment":[{"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/media?parent=27734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/categories?post=27734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ruede.de\/fr\/wp-json\/wp\/v2\/tags?post=27734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}